{"id":996,"date":"2016-07-18T18:16:06","date_gmt":"2016-07-18T18:16:06","guid":{"rendered":"http:\/\/socgastro.org.br\/novo\/?p=996"},"modified":"2016-07-18T18:16:06","modified_gmt":"2016-07-18T18:16:06","slug":"governo-americano-aprova-o-primeiro-stent-biorreabsorvivel","status":"publish","type":"post","link":"https:\/\/socgastro.org.br\/novo\/2016\/07\/governo-americano-aprova-o-primeiro-stent-biorreabsorvivel\/","title":{"rendered":"Governo americano aprova o primeiro stent biorreabsorv\u00edvel"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-997\" src=\"http:\/\/socgastro.org.br\/novo\/wp-content\/uploads\/2016\/07\/stent_absorvivel-300x180.jpg\" alt=\"stent_absorvivel\" width=\"300\" height=\"180\" \/>fonte: O Globo<\/p>\n<p>Um implante m\u00e9dico de dissolu\u00e7\u00e3o lenta no organismo pode ser a resposta aos problemas de seguran\u00e7a com dispositivos usados para tratar as art\u00e9rias obstru\u00eddas.<\/p>\n<p>O novo stent Absorb, do laborat\u00f3rio Abbott, vem com uma advert\u00eancia importante: n\u00e3o h\u00e1 demonstra\u00e7\u00e3o de que seja mais seguro do que os antigos implantes met\u00e1licos.<\/p>\n<p>A FDA, ag\u00eancia do governo americano respons\u00e1vel pelo controle de alimentos e medicamentos, aprovou o dispositivo na \u00faltima ter\u00e7a-feira para os pacientes com obstru\u00e7\u00e3o nas art\u00e9rias coron\u00e1rias, um mal que causa 370 mil mortes por ano nos Estados Unidos. O novo stent, feito com um material pl\u00e1stico, foi desenvolvido para dissolver-se ao longo de tr\u00eas anos.<\/p>\n<p>Os atuais stents s\u00e3o tubos de malha de arame que abrem as art\u00e9rias depois de uma opera\u00e7\u00e3o de remo\u00e7\u00e3o do tecido adiposo. De acordo com especialistas, o artefato desenvolvido pelo laborat\u00f3rio Abbott \u00e9 um passo importante para a busca por um melhor tratamento para a principal causa de morte nos Estados Unidos.<\/p>\n<p>\u2014 Esta parece ser uma tecnologia melhor para o futuro, pelo menos em teoria, mas levaremos anos para comprovar esta efic\u00e1cia \u2014 explica George Vetrovec, membro do conselho executivo de cardiologia da FDA.<\/p>\n<p>O Absorb, que j\u00e1 est\u00e1 \u00e0 venda na Europa e na \u00c1sia, \u00e9 fabricado com um material biorreabsorv\u00edvel que permanece intacto durante um ano e se dissolve nos dois anos seguintes.<\/p>\n<p>O uso de stents met\u00e1licos se popularizou no come\u00e7o do s\u00e9culo como tratamento para pessoas que sofreram um infarto ou tinham dor no peito causado pela obstru\u00e7\u00e3o das art\u00e9rias.<\/p>\n<p>Os m\u00e9dicos, por\u00e9m, reduziram o emprego deste artefato por raz\u00f5es de seguran\u00e7a. Estudos realizados em 2007 e 2008 revelaram que as art\u00e9rias com stents t\u00eam um risco maior de sofrer co\u00e1gulos, o que pode provocar um ataque card\u00edaco depois de um ano. Outro levantamento, realizado por cinco anos, mostrou que o tratamento com f\u00e1rmacos era t\u00e3o eficaz como o implante de um stent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>fonte: O Globo Um implante m\u00e9dico de dissolu\u00e7\u00e3o lenta no organismo pode ser a resposta aos problemas de seguran\u00e7a com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-996","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":1,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"predecessor-version":[{"id":998,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/996\/revisions\/998"}],"wp:attachment":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}