{"id":9401,"date":"2020-03-02T16:10:02","date_gmt":"2020-03-02T16:10:02","guid":{"rendered":"https:\/\/socgastro.org.br\/novo\/?p=9401"},"modified":"2020-03-02T16:10:02","modified_gmt":"2020-03-02T16:10:02","slug":"ministerio-da-saude-lanca-app-com-informacoes-para-prevencao-ao-coronavirus","status":"publish","type":"post","link":"https:\/\/socgastro.org.br\/novo\/2020\/03\/ministerio-da-saude-lanca-app-com-informacoes-para-prevencao-ao-coronavirus\/","title":{"rendered":"Minist\u00e9rio da Sa\u00fade lan\u00e7a app com informa\u00e7\u00f5es para preven\u00e7\u00e3o ao Coronav\u00edrus"},"content":{"rendered":"<p>fonte: Canal Tech<\/p>\n<p>No combate ao Coronav\u00edrus, empresas e governos t\u00eam adotado v\u00e1rias medidas de preven\u00e7\u00e3o. O SUS, por exemplo, em parceria com o Minist\u00e9rio da Sa\u00fade, est\u00e1 lan\u00e7ando um app com informa\u00e7\u00f5es \u00fateis para combate e preven\u00e7\u00e3o do Coronav\u00edrus.<\/p>\n<p>As gigantes de tecnologia, por sua vez, t\u00eam sofrido v\u00e1rias consequ\u00eancias em virtude do surto do novo Coronav\u00edrus (SARS-CoV-2) pelo mundo, especialmente na China, epicentro da doen\u00e7a, e onde est\u00e3o localizadas as f\u00e1bricas de v\u00e1rias empresas como a\u00a0Samsung\u00a0e\u00a0LG, por exemplo.<\/p>\n<p>Enquanto gigantes de tecnologia combatem o surto da doen\u00e7a em suas f\u00e1bricas, aqui no Brasil o ministro da sa\u00fade Henrique Mandetta anunciou em sua conta no Twitter, no \u00faltimo s\u00e1bado (29), o lan\u00e7amento de um aplicativo para\u00a0<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=br.gov.datasus.guardioes\" target=\"_blank\" rel=\"nofollow noopener\">Android<\/a>\u00a0e\u00a0<a href=\"https:\/\/apps.apple.com\/br\/app\/coronav%C3%ADrus-sus\/id1408008382\" target=\"_blank\" rel=\"nofollow noopener\">iOS<\/a>\u00a0chamado &#8220;Coronav\u00edrus &#8211; SUS&#8221;.<\/p>\n<p>Aplicativo Coronav\u00edrus &#8211; SUS \u00e9 uma das ferramentas do governo ao combate da doen\u00e7a (Divulga\u00e7\u00e3o). De acordo com a descri\u00e7\u00e3o na Play Store e App Store, atrav\u00e9s da plataforma \u00e9 poss\u00edvel obter tirar d\u00favidas sobre sintomas, preven\u00e7\u00e3o e outras informa\u00e7\u00f5es relevantes como unidades de sa\u00fade pr\u00f3ximas e not\u00edcias oficiais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>fonte: Canal Tech No combate ao Coronav\u00edrus, empresas e governos t\u00eam adotado v\u00e1rias medidas de preven\u00e7\u00e3o. O SUS, por exemplo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-9401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/9401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/comments?post=9401"}],"version-history":[{"count":1,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/9401\/revisions"}],"predecessor-version":[{"id":9404,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/9401\/revisions\/9404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media\/9403"}],"wp:attachment":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media?parent=9401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/categories?post=9401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/tags?post=9401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}