{"id":2770,"date":"2017-05-02T14:18:22","date_gmt":"2017-05-02T14:18:22","guid":{"rendered":"http:\/\/socgastro.org.br\/novo\/?p=2770"},"modified":"2019-02-21T10:17:06","modified_gmt":"2019-02-21T10:17:06","slug":"o-estudo-e-a-defesa-da-etica-medica-se-fazem-urgentes","status":"publish","type":"post","link":"https:\/\/socgastro.org.br\/novo\/2017\/05\/o-estudo-e-a-defesa-da-etica-medica-se-fazem-urgentes\/","title":{"rendered":"O estudo e a defesa da \u00e9tica m\u00e9dica se fazem urgentes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-188\" src=\"http:\/\/socgastro.org.br\/novo\/wp-content\/uploads\/2016\/02\/artigos_definitivo-300x166.jpg\" alt=\"\" width=\"300\" height=\"166\" \/>fonte: CFM<\/p>\n<p>por\u00a0<em>Sidnei Ferreira &#8211;\u00a02\u00ba secret\u00e1rio do Conselho Federal de Medicina (CFM)<\/em><\/p>\n<p>Em 2011, escrevi o artigo \u201cA sociedade brasileira tem um novo C\u00f3digo de \u00c9tica M\u00e9dica\u201d. Referia-se ao c\u00f3digo atual, conclu\u00eddo em 2009 e em vigor desde 2010. Estamos agora fazendo sua revis\u00e3o. Todos os m\u00e9dicos regularmente inscritos nos CRMs poder\u00e3o apresentar sugest\u00f5es. Essa revis\u00e3o se faz necess\u00e1ria para acompanhar o progresso da ci\u00eancia em geral e da medicina em particular e as mudan\u00e7as sociais e culturais das sociedades brasileira e mundial, que sucedem velozmente.<\/p>\n<p>N\u00e3o s\u00e3o muitos os of\u00edcios que t\u00eam c\u00f3digo de \u00e9tica e com import\u00e2ncia e influ\u00eancia sobre a profiss\u00e3o, como o nosso. O CEM \u00e9 uma diretriz obrigat\u00f3ria a ser seguida, protegendo o bom m\u00e9dico e a sociedade contra dificuldades que podem ocorrer, fruto, por exemplo, de quebra da rela\u00e7\u00e3o m\u00e9dico-paciente-fam\u00edlia, de capacita\u00e7\u00e3o inadequada, de desconhecimento do C\u00f3digo ou, por uma minoria de m\u00e9dicos, de m\u00e1 conduta.<\/p>\n<p>Por outro lado, poucas escolas m\u00e9dicas se preocupam em incluir na grade curricular o estudo da \u00e9tica m\u00e9dica e do CEM. Assim tem sido, tamb\u00e9m, na resid\u00eancia m\u00e9dica. Pela relev\u00e2ncia, deveria ser disciplina obrigat\u00f3ria e estar presente durante toda a gradua\u00e7\u00e3o e a p\u00f3s-gradua\u00e7\u00e3o. Sua implementa\u00e7\u00e3o se faz urgente.<\/p>\n<p>A abertura indiscriminada de escolas m\u00e9dicas, somada \u00e0 qualidade ruim do ensino, v\u00ednculos trabalhistas prec\u00e1rios, p\u00e9ssimas condi\u00e7\u00f5es de trabalho e sal\u00e1rios incompat\u00edveis com a responsabilidade e conhecimentos t\u00e9cnico-cient\u00edficos exigidos em nossa labuta di\u00e1ria, frutos da m\u00e1 gest\u00e3o, incompet\u00eancia e des\u00eddia dos gestores dos tr\u00eas n\u00edveis de governo, al\u00e9m da corrup\u00e7\u00e3o, influenciam negativamente as estat\u00edsticas de den\u00fancias e processos \u00e9tico-profissionais.<\/p>\n<p>Em novembro, em audi\u00eancia com o Ministro da Sa\u00fade na qual era solicitada interven\u00e7\u00e3o do Governo Federal no estado do Rio de Janeiro, recebemos, al\u00e9m da negativa de interven\u00e7\u00e3o ou de qualquer ajuda, a proposta para mudar a resolu\u00e7\u00e3o do CFM sobre telemedicina, retirando a obrigatoriedade de m\u00e9dico \u201cnas duas pontas\u201d, o que \u201cgeraria uma boa economia para o governo\u201d. Na semana seguinte, em reuni\u00e3o em Bras\u00edlia entre representantes da sa\u00fade do Distrito Federal, foi sugerida a flexibiliza\u00e7\u00e3o de pelo menos uma resolu\u00e7\u00e3o do CFM, a que define o dimensionamento da equipe m\u00e9dica nas urg\u00eancias e emerg\u00eancias. \u201cO governo do DF n\u00e3o pode contratar, pois ultrapassaria os limites da Lei de Responsabilidade Fiscal e, al\u00e9m disso, n\u00e3o disp\u00f5e de dinheiro para aplicar na sa\u00fade\u201d. Essas press\u00f5es, apesar de extravagantes, n\u00e3o s\u00e3o novidades e se avolumam proporcionalmente \u00e0s irresponsabilidades dos governantes.<\/p>\n<p>Emenda-se a toda hora a Constitui\u00e7\u00e3o, mudam-se leis e publicam-se medidas provis\u00f3rias por motivos muitas vezes inconfess\u00e1veis, como para favorecer e proteger corruptos, pol\u00edticos ou n\u00e3o, aumentando as desigualdades e piorando as condi\u00e7\u00f5es j\u00e1 prec\u00e1rias de atendimento \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>A solu\u00e7\u00e3o n\u00e3o \u00e9, certamente, rasgar o CEM e as resolu\u00e7\u00f5es do CFM e CRMs, colocando em risco a integridade f\u00edsica, emocional e profissional do paciente e do m\u00e9dico. Quem perdoaria um m\u00e9dico que, sozinho no plant\u00e3o, com quase uma centena e meia de atendimentos\/dia e dezenas de pacientes internados, deixasse de rever um dos pacientes em estado grave por algumas horas, resultando em \u00f3bito?<\/p>\n<p>Proteger a \u00e9tica m\u00e9dica se faz urgente, pois as \u00e9ticas pol\u00edtica e empresarial j\u00e1 terminaram faz tempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>fonte: CFM por\u00a0Sidnei Ferreira &#8211;\u00a02\u00ba secret\u00e1rio do Conselho Federal de Medicina (CFM) Em 2011, escrevi o artigo \u201cA sociedade brasileira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2],"tags":[],"class_list":["post-2770","post","type-post","status-publish","format-standard","hentry","category-artigos","category-noticias"],"_links":{"self":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/2770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/comments?post=2770"}],"version-history":[{"count":1,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/2770\/revisions"}],"predecessor-version":[{"id":2771,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/2770\/revisions\/2771"}],"wp:attachment":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media?parent=2770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/categories?post=2770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/tags?post=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}