{"id":2701,"date":"2017-04-18T10:21:33","date_gmt":"2017-04-18T10:21:33","guid":{"rendered":"http:\/\/socgastro.org.br\/novo\/?p=2701"},"modified":"2017-04-18T10:21:33","modified_gmt":"2017-04-18T10:21:33","slug":"qualidade-dos-medicamentos-genericos-produzidos-no-brasil-preocupa-o-cfm","status":"publish","type":"post","link":"https:\/\/socgastro.org.br\/novo\/2017\/04\/qualidade-dos-medicamentos-genericos-produzidos-no-brasil-preocupa-o-cfm\/","title":{"rendered":"Qualidade dos medicamentos gen\u00e9ricos produzidos no Brasil preocupa o CFM"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2411\" src=\"http:\/\/socgastro.org.br\/novo\/wp-content\/uploads\/2017\/02\/cfm_brasilia-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>fonte: CFM<\/p>\n<p>A efic\u00e1cia dos medicamentos gen\u00e9ricos produzidos no Brasil \u00e9 tema de preocupa\u00e7\u00e3o para o Conselho Federal de Medicina (CFM). O Tribunal de Contas da Uni\u00e3o (TCU) divulgou, em outubro de 2016, o resultado de uma auditoria realizada por solicita\u00e7\u00e3o do Congresso Nacional (PFC 170\/2014) com base em \u201cden\u00fancias de profissionais de sa\u00fade e de consumidores no sentido de que a efic\u00e1cia do medicamento gen\u00e9rico seria limitada\u201d.<\/p>\n<p>As queixas informavam, inclusive, a \u201cnecessidade de substitui\u00e7\u00e3o dos gen\u00e9ricos, no meio do tratamento, por n\u00e3o surtirem os efeitos esperados para os princ\u00edpios ativos\u201d. Sob relatoria do ministro Bruno Dantas, a auditoria concluiu que h\u00e1 fragilidades no monitoramento e fiscaliza\u00e7\u00e3o realizados pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) dos medicamentos comercializados no Pa\u00eds.<\/p>\n<p>\u201c\u00c9 de extrema relev\u00e2ncia termos \u00e0 disposi\u00e7\u00e3o da popula\u00e7\u00e3o m\u00faltiplos laborat\u00f3rios produzindo o mesmo medicamento, que \u00e9 o caso dos gen\u00e9ricos. No entanto, s\u00f3 h\u00e1 de fato benef\u00edcio se todos os rem\u00e9dios dispon\u00edveis no mercado cumprirem sua fun\u00e7\u00e3o no tratamento do paciente, se efetivamente tiverem qualidade\u201d, ressalta <em>Hermann von Tiesenhausen<\/em>, 1\u00ba secret\u00e1rio do CFM.<\/p>\n<p><strong>Cancelamentos<\/strong> \u2013 Em nota recente, publicada em resposta a not\u00edcias sobre medicamentos gen\u00e9ricos, a Anvisa afirmou manter seu posicionamento: \u201cos medicamentos gen\u00e9ricos a que os brasileiros t\u00eam acesso s\u00e3o seguros\u201d. Dados da pr\u00f3pria autarquia revelam que, de janeiro de 2000 a agosto de 2016, 4.661 medicamentos gen\u00e9ricos foram registrados no Pa\u00eds. Contudo, desse total, 861 foram cancelados, restando 3.800 medicamentos gen\u00e9ricos de 114 empresas detentoras de registros v\u00e1lidos no Brasil.<\/p>\n<p>De acordo com a Anvisa, as principais vantagens dos gen\u00e9ricos s\u00e3o: \u201cdisponibilizar medicamentos de menor pre\u00e7o, uma vez que o medicamento gen\u00e9rico deve ser, no m\u00ednimo, 35% mais barato que o medicamento de refer\u00eancia; reduzir os pre\u00e7os dos medicamentos de refer\u00eancia, com a entrada de medicamentos concorrentes (gen\u00e9ricos); contribuir para aumento do acesso a medicamentos de qualidade, seguros e eficazes\u201d.<\/p>\n<p><strong>Crit\u00e9rios<\/strong> \u2013 O medicamento gen\u00e9rico deve conter os mesmos princ\u00edpios ativos, forma farmac\u00eautica, dose, via de administra\u00e7\u00e3o, posologia e indica\u00e7\u00e3o terap\u00eautica do medicamento de refer\u00eancia, sendo, assim, intercambi\u00e1vel por garantir a mesma efic\u00e1cia e seguran\u00e7a. Para entrarem no mercado, os gen\u00e9ricos s\u00e3o submetidos a testes em laborat\u00f3rios credenciados pela Anvisa afim de confirmar a bioequival\u00eancia (conter id\u00eantica composi\u00e7\u00e3o qualitativa e quantitativa de princ\u00edpio ativo) e compar\u00e1vel biodisponibilidade (velocidade e extens\u00e3o de absor\u00e7\u00e3o de um princ\u00edpio ativo a partir de sua curva concentra\u00e7\u00e3o\/tempo na circula\u00e7\u00e3o sist\u00eamica ou sua excre\u00e7\u00e3o na urina).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>fonte: CFM A efic\u00e1cia dos medicamentos gen\u00e9ricos produzidos no Brasil \u00e9 tema de preocupa\u00e7\u00e3o para o Conselho Federal de Medicina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2701","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":1,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/2701\/revisions"}],"predecessor-version":[{"id":2702,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/2701\/revisions\/2702"}],"wp:attachment":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/categories?post=2701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/tags?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}