{"id":15018,"date":"2022-08-03T10:56:08","date_gmt":"2022-08-03T10:56:08","guid":{"rendered":"https:\/\/socgastro.org.br\/novo\/?p=15018"},"modified":"2022-07-11T10:58:13","modified_gmt":"2022-07-11T10:58:13","slug":"artigo-saude-suplementar-ate-quando-vamos-conseguir-pagar-a-conta","status":"publish","type":"post","link":"https:\/\/socgastro.org.br\/novo\/2022\/08\/artigo-saude-suplementar-ate-quando-vamos-conseguir-pagar-a-conta\/","title":{"rendered":"ARTIGO: Sa\u00fade Suplementar: at\u00e9 quando vamos conseguir pagar a conta?"},"content":{"rendered":"<p>fonte: <a href=\"https:\/\/www1.folha.uol.com.br\/blogs\/saude-em-publico\/2022\/07\/saude-suplementar-ate-quando-vamos-conseguir-pagar-a-conta.shtml?\" target=\"_blank\" rel=\"noopener\">Folha de SP<\/a><\/p>\n<p>por Adriana Monteiro da Silva, Camilla Varella Guimar\u00e3es, Joanna Maria de Ara\u00fajo Sampaio, advogadas signat\u00e1rias da <a href=\"https:\/\/portal.stf.jus.br\/processos\/detalhe.asp?incidente=6425744\" target=\"_blank\" rel=\"noopener\">A\u00e7\u00e3o Direta de Inconstitucionalidade n\u00ba 7183<\/a><\/p>\n<div class=\"c-news__body\" data-share-text=\"\" data-news-content-text=\"\" data-disable-copy=\"\" data-continue-reading=\"\" data-continue-reading-hide-others=\".js-continue-reading-hidden\" data-age-rating=\"all\">\n<p>Acompanhamos no \u00faltimo m\u00eas a discuss\u00e3o sobre a taxatividade do rol da ANS, tendo a<i>\u00a0hashtag\u00a0<\/i>#roltaxativomata ficado entre as mais usadas nas redes sociais. No dia 8 de junho, no entanto, o Superior Tribunal de Justi\u00e7a (STJ) declarou que o rol da ANS \u00e9, em regra, taxativo. Este entendimento limita a prote\u00e7\u00e3o \u00e0 sa\u00fade a uma lista restrita de procedimentos m\u00e9dicos. Desde ent\u00e3o, as operadoras de sa\u00fade iniciaram uma cruzada para interromper tratamentos m\u00e9dicos que estavam garantidos por liminares judiciais.<\/p>\n<p>Mas afinal: a decis\u00e3o proferida pelo STJ vai de fato prejudicar os 50 milh\u00f5es de brasileiros que t\u00eam plano de sa\u00fade?<\/p>\n<p>A resposta \u00e9 sim, j\u00e1 est\u00e1 prejudicando. Os pacientes com c\u00e2ncer, por exemplo, passaram a ter negados exames de\u00a0<i>PET scan<\/i>\u00a0(fundamentais para diagn\u00f3stico e acompanhamento da doen\u00e7a), porque n\u00e3o constam do Rol da ANS. As Operadoras de Sa\u00fade v\u00eam negando tratamentos, exames e at\u00e9 oxig\u00eanio a usu\u00e1rios de\u00a0<i>homecare<\/i>. O atleta Gildo Afonso, que sofre de esclerose m\u00faltipla, teve seu tratamento com o f\u00e1rmaco Kesimpta suspenso, com a justificativa de n\u00e3o estar previsto no tal rol.<\/p>\n<p>Estes s\u00e3o alguns dos exemplos do desamparo dos brasileiros que motivou o CRPD (Comit\u00ea Brasileiro de Organiza\u00e7\u00f5es Representativas das Pessoas com Defici\u00eancia) a ingressar com a A\u00e7\u00e3o Direta de Inconstitucionalidade n\u00ba 7183 perante o Supremo Tribunal Federal, a fim de corrigir a injusti\u00e7a representada pelo Rol Taxativo da ANS.<\/p>\n<p>O plano de sa\u00fade \u00e9 uma renda indireta, j\u00e1 que se desconta o valor mensal do contracheque para resguardar a sa\u00fade do trabalhador e sua fam\u00edlia. Ora, n\u00e3o se trata apenas de uma benevol\u00eancia do sistema, mas de prote\u00e7\u00e3o tamb\u00e9m da sa\u00fade do capital. Trabalhador doente n\u00e3o produz. Sabe-se do sacrif\u00edcio das fam\u00edlias para arcarem com os altos custos de um plano, comprometendo muitas vezes o or\u00e7amento da pr\u00f3pria alimenta\u00e7\u00e3o para garantir um atendimento de sa\u00fade digno.<\/p>\n<p>Como chegamos a esse ponto? Muito simples: as operadoras conseguiram convencer parte do Judici\u00e1rio sem jamais terem comprovado que o sistema de sa\u00fade suplementar vai colapsar caso tenha que cobrir tratamentos n\u00e3o previstos no Rol da ANS.<\/p>\n<p>Trata-se da maior\u00a0<i>fake news<\/i>\u00a0dos \u00faltimos tempos, j\u00e1 que desde 1998 (quando publicada a Lei dos Planos de Sa\u00fade) as Operadoras vinham arcando com tratamentos n\u00e3o previstos no rol, por for\u00e7a de decis\u00f5es corajosas do Poder Judici\u00e1rio e, nem por isso, deixaram de lucrar.<\/p>\n<p>Para se ter uma ideia, a Unimed Campinas (que foi parte no processo que definiu a taxatividade do rol da ANS), fechou 2020 com um\u00a0faturamento\u00a0de 2,5 bilh\u00f5es de reais \u2013 aumento de 1,5% em rela\u00e7\u00e3o a 2019.<\/p>\n<p>Ao contr\u00e1rio da promessa de que um rol taxativo diminuiria os custos dos planos de sa\u00fade, a ANS aprovou o reajuste de 15,5% nos planos de sa\u00fade individuais e familiares. J\u00e1 os planos empresariais que n\u00e3o se sujeitam \u00e0 regra, os\u00a0reajustes chegam a 133%.<\/p>\n<p>O Tribunal de Contas da Uni\u00e3o (TCU), na Auditoria 021.852\/2014-6, deixa claro que a ANS vem falhando sistematicamente no seu papel de ag\u00eancia reguladora. Segundo o TCU, a ANS n\u00e3o possui mecanismos adequados para preven\u00e7\u00e3o e corre\u00e7\u00e3o de reajustes abusivos em planos coletivos e individuais.<\/p>\n<p>Ademais, restou provado que a ANS tem adicionado uma parcela extra ao percentual m\u00e1ximo de reajuste para compensa\u00e7\u00e3o de fatores ex\u00f3genos, que (pasmem!) j\u00e1 foram considerados no c\u00e1lculo base, levando ao duplo impacto dos valores do \u00edndice de reajuste.<\/p>\n<p>Reajustes exorbitantes impactam diretamente a renda de trabalhadores e aposentados, que precisam de malabarismos para pagar despesas di\u00e1rias, sem contrapartida de cuidado integral pelos planos. A Constitui\u00e7\u00e3o protege o direito \u00e0 sa\u00fade e \u00e0 vida como fundamentais, que devem ser garantidos tanto pela sa\u00fade suplementar quanto pela p\u00fablica. Assim, ainda que busque ganhos financeiros, a iniciativa privada n\u00e3o deve colocar o interesse econ\u00f4mico acima da prote\u00e7\u00e3o \u00e0 sa\u00fade.<\/p>\n<p>A Lei\u00a0<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2019-2022\/2022\/Lei\/L14307.htm\">14.307<\/a>, de mar\u00e7o deste ano, teve por objetivo apoiar a argumenta\u00e7\u00e3o a favor do rol taxativo ao, supostamente, dispor de crit\u00e9rios t\u00e9cnicos para a elabora\u00e7\u00e3o do rol. Dentre os tr\u00eas crit\u00e9rios para adicionar um novo procedimento \u00e0 lista, dois deles protegem os interesses econ\u00f4micos das operadoras de sa\u00fade: a avalia\u00e7\u00e3o econ\u00f4mica do custo-benef\u00edcio e o impacto financeiro do procedimento. Os interesses econ\u00f4micos tamb\u00e9m regem a composi\u00e7\u00e3o da Comiss\u00e3o de Atualiza\u00e7\u00e3o do rol. As operadoras possuem dois assentos representativos, enquanto os 50 milh\u00f5es de consumidores apenas um.<\/p>\n<p>Enquanto esse entendimento permanecer, v\u00e1rias quest\u00f5es restam em aberto. Quantos conseguir\u00e3o pagar um plano que, paradoxalmente, n\u00e3o assegura a sa\u00fade? Como um SUS sobrecarregado pelo n\u00e3o atendimento da rede privada poder\u00e1 funcionar adequadamente? At\u00e9 quando teremos a sa\u00fade garantida? Qual o pre\u00e7o de nossas vidas?<\/p>\n<p>Neste momento, esta resposta est\u00e1 nas m\u00e3os do STF, especificamente do Ministro Lu\u00eds Roberto Barroso, que tem a possibilidade de corrigir esse cen\u00e1rio injusto, que faz com que 50 milh\u00f5es de brasileiros paguem planos de sa\u00fade, sem a certeza do que os espera.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>fonte: Folha de SP por Adriana Monteiro da Silva, Camilla Varella Guimar\u00e3es, Joanna Maria de Ara\u00fajo Sampaio, advogadas signat\u00e1rias da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13317,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/15018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/comments?post=15018"}],"version-history":[{"count":1,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/15018\/revisions"}],"predecessor-version":[{"id":15020,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/15018\/revisions\/15020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media\/13317"}],"wp:attachment":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media?parent=15018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/categories?post=15018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/tags?post=15018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}