{"id":1222,"date":"2016-08-15T21:19:55","date_gmt":"2016-08-15T21:19:55","guid":{"rendered":"http:\/\/socgastro.org.br\/novo\/?p=1222"},"modified":"2016-08-15T21:19:55","modified_gmt":"2016-08-15T21:19:55","slug":"um-terco-dos-homens-nao-acompanha-estado-de-saude","status":"publish","type":"post","link":"https:\/\/socgastro.org.br\/novo\/2016\/08\/um-terco-dos-homens-nao-acompanha-estado-de-saude\/","title":{"rendered":"Um ter\u00e7o dos homens n\u00e3o acompanha estado de sa\u00fade"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-95\" src=\"http:\/\/socgastro.org.br\/novo\/wp-content\/uploads\/2016\/01\/medicina-300x225.jpg\" alt=\"medicina\" width=\"300\" height=\"225\" \/>fonte: Minist\u00e9rio da Sa\u00fade<\/p>\n<div>Quase um ter\u00e7o (31%) dos homens brasileiros n\u00e3o tem o h\u00e1bito de ir aos servi\u00e7os de sa\u00fade para acompanhar seu estado de sa\u00fade e buscar aux\u00edlio na preven\u00e7\u00e3o de doen\u00e7as e na qualidade de vida. Pesquisa realizada pelo Minist\u00e9rio da Sa\u00fade aponta que barreiras socioculturais interferem na preven\u00e7\u00e3o \u00e0 sa\u00fade. Em muitos casos, os homens pensam que n\u00e3o ficam doentes ou t\u00eam medo de descobrir doen\u00e7a, al\u00e9m de sentirem que esse cuidado pode interferir na sua imagem de cuidado com a fam\u00edlia.<\/div>\n<div><\/div>\n<div>\u201cSa\u00fade \u00e9 importante para que os homens participem ativamente das atividades familiares. Nossa chamada \u00e9 para que os pais procurem os servi\u00e7os e recebam orienta\u00e7\u00f5es para cuidar de sua sa\u00fade e prevenir doen\u00e7as, como manter as vacinas em dia. Filhos, lembrem seus pais de cuidar regularmente da sa\u00fade. Esse ser\u00e1 o melhor presente para toda a fam\u00edlia\u201d, afirmou o ministro da Sa\u00fade, Ricardo Barros.<\/div>\n<div><\/div>\n<div>Uma das respostas mais comuns entre os homens (55%) \u00e9 dizer que n\u00e3o buscaram os servi\u00e7os de sa\u00fade, pois nunca precisaram. Essa falta de cuidado, no entanto, esconde uma crescente consequ\u00eancia para a maioria dos brasileiros: eles morrem mais cedo do que as mulheres e de doen\u00e7as que poderiam ser prevenidas, como acidentes vasculares, infartos, c\u00e2nceres e doen\u00e7as do aparelho digestivo.<\/div>\n<div><\/div>\n<div>A partir deste diagn\u00f3stico e aproveitando a semana em que se comemora o Dia dos Pais, o Minist\u00e9rio da Sa\u00fade lan\u00e7a o Guia do Pr\u00e9-Natal do parceiro e o Guia da Sa\u00fade do Homem para agente comunit\u00e1rio de sa\u00fade. O objetivo \u00e9 aproveitar o momento em que o homem est\u00e1 mais pr\u00f3ximo do servi\u00e7o de sa\u00fade, acompanhando sua parceira no Pr\u00e9-Natal, para que ele adote h\u00e1bitos saud\u00e1veis e realize exames preventivos. Como a chegada de um filho traz mudan\u00e7as \u00e0 fam\u00edlia, a ideia \u00e9 despertar nos futuros pais a necessidade de ado\u00e7\u00e3o de medidas preventivas que lhe garantam um futuro ao lado dos filhos.<\/div>\n<div><\/div>\n<div>\u201cAlguns pilotos de capacita\u00e7\u00e3o com profissionais de sa\u00fade j\u00e1 foram feitos na Bahia, S\u00e3o Paulo e Paran\u00e1. Nossa ideia \u00e9 mostrar a forma triangular da fam\u00edlia e sair daquele bin\u00f4mio m\u00e3e e filho. Algumas unidades de sa\u00fade j\u00e1 atendem em hor\u00e1rio ampliado para atrair os homens\u201d, informa Francisco Norberto, coordenador da sa\u00fade do homem.<\/div>\n<div><\/div>\n<div>A pesquisa mostrou ainda que, apesar do Pr\u00e9-natal da parceira ser o momento em que o homem est\u00e1 mais pr\u00f3ximo do servi\u00e7o de sa\u00fade, ele ainda \u00e9 pouco aproveitado pelos profissionais. A maioria dos homens (80%) disse que acompanhou a parceira nas consultas de pr\u00e9-natal, mas 56% disseram que o atendimento teve foco apenas nas orienta\u00e7\u00f5es para a gestante.<\/div>\n<div><\/div>\n<div>Sobre a realiza\u00e7\u00e3o de exames, 84,6% dos pais n\u00e3o realizaram nenhum durante o pr\u00e9-natal. Os exames mais pedidos para os que realizaram foram tipagem sangu\u00ednea (70,4%), seguido da sorologia para HIV e hemograma. Tamb\u00e9m foi alto o percentual de homens que informaram que n\u00e3o atualizaram o seu cart\u00e3o de vacinas \u2013 64%. Quanto \u00e0s orienta\u00e7\u00f5es sobre planejamento familiar, 61% relataram ter recebido atendimento nos servi\u00e7os de sa\u00fade.<\/div>\n<div><\/div>\n<div>O inqu\u00e9rito telef\u00f4nico foi realizado em 2015, com mais de seis mil homens cujas parceiras fizeram parto no SUS. Dentre os participantes, 80% tinham entre 20 e 39 anos e 67,3% afirmaram ter renda entre 1 e 2 sal\u00e1rios m\u00ednimos. Quase metade (49%) relataram que s\u00e3o casados e apenas 36,9% possu\u00edam n\u00edvel m\u00e9dio completo.<\/div>\n<div><\/div>\n<div>O Minist\u00e9rio da Sa\u00fade tamb\u00e9m lan\u00e7ou com a Avasus um curso a dist\u00e2ncia chamado Pai Presente \u2013 Cuidado e Compromisso. O curso \u00e9 voltado para todos os pais que querem viver uma paternidade ativa e consciente. Quem tiver interesse, o endere\u00e7o \u00e9 https:\/\/avasus.ufrn.br\/<\/div>\n<div><\/div>\n<div>SA\u00daDE DO HOMEM \u2013 O resultado da busca tardia pelo servi\u00e7o de sa\u00fade \u00e9 que, em m\u00e9dia, os homens vivem sete anos a menos que as mulheres. Segundo a \u00faltima pesquisa do IBGE, enquanto a expectativa de vida dos homens alcan\u00e7ou 71 anos, entre as mulheres, a expectativa \u00e9 de 78 anos. As causas que mais matam os homens s\u00e3o as externas, (acidentes de tr\u00e2nsito, viol\u00eancias), seguido de doen\u00e7as do aparelho circulat\u00f3rio, neoplasias e aparelho digestivo. Ou seja, males que, se conhecidos no est\u00e1gio inicial, podem ser prevenidos ou controlados.<\/div>\n<div><\/div>\n<div>Dados do Vigitel 2015 mostraram ainda outros problemas de sa\u00fade. No quesito da nutri\u00e7\u00e3o, 57% dos homens t\u00eam sobrepeso e 18% est\u00e3o obesos, 25% deles consomem bebidas alc\u00f3olicas, 13% deles fumam e apenas 31% consomem regularmente frutas e verduras.<\/div>\n<div><\/div>\n<div>O governo brasileiro foi o primeiro das Am\u00e9ricas a desenvolver e executar uma pol\u00edtica exclusiva para homens. Atualmente, al\u00e9m do Brasil, apenas a Austr\u00e1lia e Irlanda apresentam uma pol\u00edtica com a mesma finalidade.<\/div>\n<div><\/div>\n<div>Agora, com o Guia do Pr\u00e9-Natal do Parceiro para Profissionais de Sa\u00fade e o Guia da Sa\u00fade do Homem para o Agente Comunit\u00e1rio de Sa\u00fade (ACS), o Minist\u00e9rio da Sa\u00fade quer estimular os homens a assumirem cuidados preventivos \u2013 no m\u00eas que \u00e9 marcado, no Brasil, pelo Dia dos Pais e que, por isso, foi adotado como m\u00eas de valoriza\u00e7\u00e3o da paternidade. \u201cGravidez tamb\u00e9m \u00e9 assunto de homem. Estimular a participa\u00e7\u00e3o do parceiro \u00e9 fundamental para o bem estar da m\u00e3e, do beb\u00ea e do pr\u00f3prio homem\u201d, afirma o coordenador da sa\u00fade do homem, Francisco Norberto.<\/div>\n<div><\/div>\n<div>J\u00e1 o Guia da Sa\u00fade do Homem do Agente Comunit\u00e1rio de Sa\u00fadetem o prop\u00f3sito desensibilizar os ACS\u2019s no sentido de levar o homem \u00e0s unidades b\u00e1sicas de sa\u00fade para trabalhar a preven\u00e7\u00e3o. \u201cNossa inten\u00e7\u00e3o \u00e9 educar o homem para que ele entenda as unidades de sa\u00fade como um espa\u00e7o de cuidado\u201d, completa o coordenador.<\/div>\n<div><\/div>\n<div>As publica\u00e7\u00f5es ser\u00e3o apresentadas em capacita\u00e7\u00f5es que acontecer\u00e3o em todo o pa\u00eds de agosto a novembro deste ano. Ser\u00e3o distribu\u00eddos 242.500 exemplares do Guia do Pr\u00e9-Natal do Parceiro para Profissionais de Sa\u00fade, voltado para inser\u00e7\u00e3o dos homens no pr\u00e9-natal de suas parceiras. Ele orienta e incentiva o homem a exercer a paternidade desde o planejamento reprodutivo do casal, passando pela fase do pr\u00e9-natal, parto e aten\u00e7\u00e3o \u00e0s crian\u00e7as.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>fonte: Minist\u00e9rio da Sa\u00fade Quase um ter\u00e7o (31%) dos homens brasileiros n\u00e3o tem o h\u00e1bito de ir aos servi\u00e7os de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1222","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":1,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"predecessor-version":[{"id":1223,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/posts\/1222\/revisions\/1223"}],"wp:attachment":[{"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socgastro.org.br\/novo\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}